{"id":3267,"date":"2022-01-12T16:40:42","date_gmt":"2022-01-12T15:40:42","guid":{"rendered":"https:\/\/raumluft24.de\/?p=3267"},"modified":"2025-01-30T16:28:13","modified_gmt":"2025-01-30T15:28:13","slug":"22-02-08-viren-beseitigen-mit-uv-c-licht","status":"publish","type":"post","link":"https:\/\/raumluft24.de\/es\/22-02-08-viren-beseitigen-mit-uv-c-licht\/","title":{"rendered":"Eliminar los virus con luz UV-C"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; custom_margin=&#8220;0px||0px||true|false&#8220; custom_padding=&#8220;0px|0px|0px|0px|true|true&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;30px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Erster Textabschnitt&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font_size_last_edited=&#8220;off|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Wenn Sie sich gesund halten m\u00f6chten, ist es f\u00fcr Sie sicherlich selbstverst\u00e4ndlich, Ihr Zuhause durch regelm\u00e4\u00dfige Reinigung und Desinfektion sauber und keimfrei zu halten. Insbesondere Oberfl\u00e4chen und Griffe werden dabei gr\u00fcndlich gereinigt. Sp\u00e4testens seit der Corona-Pandemie ist uns allen aber auch bewusst geworden, welch wichtige Rolle die Virenbelastung unserer Atemluft spielt.<\/p>\n<p>Beim Husten und Niesen werden n\u00e4mlich Tropfen, die Viren enthalten k\u00f6nnen, zun\u00e4chst in die Luft geschleudert. Gro\u00dfe, schwere Tropfen sinken recht z\u00fcgig auf den Boden oder Gegenst\u00e4nde ab. Kleinere k\u00f6nnen jedoch mehrere Stunden oder sogar Tage in der Luft schweben. Sie k\u00f6nnen diese daher nicht selbst reinigen, sondern m\u00fcssen auf technische Hilfsmittel zur\u00fcckgreifen. Seit Jahrzehnten bew\u00e4hrt sich daf\u00fcr eine L\u00f6sung, die z. B. auch im medizinischen Bereich eingesetzt wird, mit der Sie Ihre Raumluft sauber und sich selbst damit ein St\u00fcck ges\u00fcnder halten k\u00f6nnen: UV-C-Licht!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,2_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|tablet&#8220; _builder_version=&#8220;4.16&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_direction=&#8220;-268deg&#8220; background_color_gradient_stops=&#8220;#40cb67 0%|#0587c3 100%&#8220; background_color_gradient_start=&#8220;#40cb67&#8243; background_color_gradient_end=&#8220;#0587c3&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_margin=&#8220;30px||30px||true|false&#8220; custom_margin_tablet=&#8220;20px||20px||true|false&#8220; custom_margin_phone=&#8220;10px||10px||true|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;50px|10px|50px|15px|true|false&#8220; custom_padding_tablet=&#8220;40px||40px||true|true&#8220; custom_padding_phone=&#8220;30px||30px||true|true&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_blur=&#8220;19px&#8220; box_shadow_color=&#8220;rgba(0,0,0,0.25)&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; custom_css_main_element=&#8220;display: -webkit-box;||display: -ms-flexbox;||display: flex;||-webkit-box-align: center;||    -ms-flex-align: center;||        align-items: center;||-webkit-box-pack: center;||    -ms-flex-pack: center;||        justify-content: center;&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Quicksand|700||on|||||&#8220; text_font_size=&#8220;24px&#8220; text_line_height=&#8220;1.5em&#8220; text_orientation=&#8220;center&#8220; background_layout=&#8220;dark&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Das Wichtigste<br \/>im \u00dcberblick<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; custom_css_main_element=&#8220;display: -webkit-box;||display: -ms-flexbox;||display: flex;||-webkit-box-align: center;||    -ms-flex-align: center;||        align-items: center;||-webkit-box-pack: center;||    -ms-flex-pack: center;||        justify-content: center;&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text ul_position=&#8220;inside&#8220; module_class=&#8220;specialcheck&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|600|||||||&#8220; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;2em&#8220; ul_font=&#8220;|600|||||||&#8220; ul_font_size=&#8220;17px&#8220; ul_line_height=&#8220;2em&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; custom_css_main_element=&#8220;display: -webkit-box;||display: -ms-flexbox;||display: flex;||-webkit-box-align: center;||    -ms-flex-align: center;||        align-items: center;||-webkit-box-pack: center;||    -ms-flex-pack: center;||        justify-content: center;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<ul class=\"check\">\n<li>UV-Licht ist f\u00fcr das menschliche Auge unsichtbar<\/li>\n<li>UV-Licht eliminiert Bakterien und Viren<\/li>\n<li>Luftreinigung durch UV-C Licht mit multifunktioneller Klimaanlage<\/li>\n<li>Auch geeignet f\u00fcr gro\u00dfe R\u00e4ume bis zu 60 m\u00b2<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;30px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; header_2_font=&#8220;|600||on|||||&#8220; header_2_font_size=&#8220;25px&#8220; header_2_line_height=&#8220;1.3em&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Wie funktioniert die Luftreinigung mit UV-C-Licht?<\/h2>\n<p><a href=\"https:\/\/raumluft24.de\/wp-content\/uploads\/2022\/02\/3d58fc6d-7d64-45e5-b492-7e303062334d.jpg\"><img decoding=\"async\" src=\"https:\/\/raumluft24.de\/wp-content\/uploads\/2022\/02\/3d58fc6d-7d64-45e5-b492-7e303062334d.jpg\" width=\"400\" height=\"267\" alt=\"Klimaanlage mit UV-C Licht\" class=\"wp-image-3542 alignleft size-full\" \/><\/a>Ultraviolettes Licht ist f\u00fcr das menschliche Auge nicht sichtbar. Vielleicht wissen Sie, dass dieses Licht auch im Solarium zum Einsatz kommt. Allerdings handelt es sich dabei um die l\u00e4ngeren Strahlenarten UV-A und UV-B. Die k\u00fcrzeste Wellenl\u00e4nge, die UV-C-Strahlung, ist hingegen das Licht, welches eingesetzt wird, um Wasser, Gegenst\u00e4nde und die Luft zu desinfizieren. Lebewesen sollten diesem Licht nicht permanent ausgesetzt werden, da die Hautalterung dadurch beschleunigt werden kann.<\/p>\n<p>Eingebaut in Klimaanlagen wird die Luft aber vollkommen sicher innerhalb des Ger\u00e4ts an den UV-C-Lampen vorbeigeschleust, womit keine Gefahr f\u00fcr anwesende Personen im Raum besteht.<\/p>\n<p>Es ist eine \u00e4u\u00dferst effektive Methode, um diverse Krankheitserreger wie Viren, Bakterien und Schimmelpilze abzut\u00f6ten: Die UV-Lampe kann bis zu 99,9 % der enthaltenen Bakterien und Viren abt\u00f6ten, indem es die molekularen Bestandteile der Mikroorganismen zerst\u00f6rt. Innerhalb von Sekunden werden diese inaktiv. Diese Art der Desinfektion birgt den Vorteil, ohne den Einsatz gef\u00e4hrlicher chemischer Substanzen auszukommen!<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; header_2_font=&#8220;|600||on|||||&#8220; header_2_font_size=&#8220;25px&#8220; header_2_line_height=&#8220;1.3em&#8220; custom_margin=&#8220;35px||||false|false&#8220; custom_margin_tablet=&#8220;25px||||false|false&#8220; custom_margin_phone=&#8220;25px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Klimaanlagen Malpensa und Elba Mini reinigen Luft mit UV-Technik!<\/h2>\n<p><a href=\"https:\/\/raumluft24.de\/wp-content\/uploads\/2021\/01\/klimageraet_inhp8.jpg\"><img decoding=\"async\" src=\"https:\/\/raumluft24.de\/wp-content\/uploads\/2021\/01\/klimageraet_inhp8.jpg\" width=\"400\" height=\"267\" alt=\"Klimaanlagen Malpensa und Elba Mini beseitigen Viren mit UV-C-Licht\" class=\"wp-image-147 alignleft size-full\" \/><\/a>Wenn Sie gerne f\u00fcr hygienisch reine Luft bei Ihnen Zuhause oder in gewerblichen R\u00e4umen sorgen wollen, empfehlen wir Ihnen unsere <a href=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-malpensa-in12hp-uv\/\" title=\"Wandklimaanlage Malpensa mit integrierter UV-C-Lampe in unserem Shop ansehen\">Wandklimaanlage Malpensa mit integrierter UV-C-Lampe<\/a> sowie unsere <a href=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-elba-mini-inhp09-mit-uv-technik\/\" title=\"Klimaanlage Elba Mini mit integrierter UV-C Lampe in unserem Shop ansehen\">Klimaanlage Elba Mini mit integrierter UV-C Lampe<\/a>. Die Multifunktions-Klimager\u00e4te k\u00f6nnen selbstverst\u00e4ndlich zum K\u00fchlen und Heizen genutzt werden, haben eine Luftentfeuchtungsfunktion und sorgen gleichzeitig f\u00fcr eine effektive Abt\u00f6tung von Krankheitserregern in der Raumluft mittels UV-Entkeimung. Neben der Installation in Privatr\u00e4umen f\u00fcr die eigene Gesundheit, bietet sich die Klimaanlage mit UV-Lampe auch im Hotelgewerbe an, um die Aerosole wechselnder Hotelg\u00e4ste zu neutralisieren. Zudem sind die Klimaanlagen Malpensa und Elba Mini f\u00fcr R\u00e4ume von 30 m\u00b2 &#8211; 60 m\u00b2 &shy;\u00a0geeignet, wodurch das Produkt auch f\u00fcr Klassenr\u00e4ume, kleinere Gastronomie-Betriebe sowie B\u00fcros oder Besprechungsr\u00e4ume interessant ist.<\/p>\n<p>Wie bei unseren Wandklimager\u00e4ten \u00fcblich, sind auch die Modelle Malpensa und Elba Mini leistungsstark und dabei extrem leise (27 &#8211; 43 Dezibel). Die Installation ist einfach und schnell und erfolgt vor allem ohne Au\u00dfenger\u00e4t an Ihrer Fassade. Sie k\u00f6nnen die Montageh\u00f6he grunds\u00e4tzlich selbst w\u00e4hlen. Mit ihrer wei\u00dfen Lackierung und dem schlichten Monoblock-Design sehen die Klimaanlagen Malpensa und Elba Mini schick und unaufdringlich aus.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;30px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/raumluft24.de\/wp-content\/uploads\/2021\/06\/raumluft24-wohnzimmer-fenster.jpg&#8220; alt=&#8220;Malpensa mit UV-C-Licht&#8220; align=&#8220;center&#8220; force_fullwidth=&#8220;on&#8220; module_class=&#8220;promo-images-243height&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; max_height=&#8220;243px&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_vertical=&#8220;0px&#8220; box_shadow_blur=&#8220;27px&#8220; box_shadow_color=&#8220;rgba(0,0,0,0.16)&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wcm9kdWN0Iiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE2MDIifX0=@&#8220; button_text=&#8220;MALPENSA im Shop ansehen&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#FFFFFF&#8220; button_bg_use_color_gradient=&#8220;on&#8220; button_bg_color_gradient_direction=&#8220;90deg&#8220; button_bg_color_gradient_stops=&#8220;#2487c3 0%|#47d26e 100%&#8220; button_bg_color_gradient_start=&#8220;#2487c3&#8243; button_bg_color_gradient_end=&#8220;#47d26e&#8220; button_font=&#8220;|700|||||||&#8220; button_icon=&#8220;&#x39;||divi||400&#8243; button_on_hover=&#8220;off&#8220; background_layout=&#8220;dark&#8220; custom_padding=&#8220;|2.5em|||false|false&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_vertical=&#8220;0px&#8220; box_shadow_blur=&#8220;41px&#8220; box_shadow_color=&#8220;rgba(0,226,208,0.34)&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/raumluft24.de\/wp-content\/uploads\/2021\/06\/raumluft24-wohnzimmer.jpg&#8220; alt=&#8220;Elba Mini mit UV-C-Licht&#8220; align=&#8220;center&#8220; force_fullwidth=&#8220;on&#8220; module_class=&#8220;promo-images-243height&#8220; _builder_version=&#8220;4.17.4&#8243; _module_preset=&#8220;default&#8220; max_height=&#8220;230px&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_vertical=&#8220;0px&#8220; box_shadow_blur=&#8220;27px&#8220; box_shadow_color=&#8220;rgba(0,0,0,0.16)&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wcm9kdWN0Iiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI5MjQifX0=@&#8220; button_text=&#8220;ELBA Mini im Shop ansehen&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#FFFFFF&#8220; button_bg_use_color_gradient=&#8220;on&#8220; button_bg_color_gradient_direction=&#8220;90deg&#8220; button_bg_color_gradient_stops=&#8220;#2487c3 0%|#47d26e 100%&#8220; button_bg_color_gradient_start=&#8220;#2487c3&#8243; button_bg_color_gradient_end=&#8220;#47d26e&#8220; button_font=&#8220;|700|||||||&#8220; button_icon=&#8220;&#x39;||divi||400&#8243; button_on_hover=&#8220;off&#8220; background_layout=&#8220;dark&#8220; custom_padding=&#8220;|2.5em|||false|false&#8220; box_shadow_style=&#8220;preset1&#8243; box_shadow_vertical=&#8220;0px&#8220; box_shadow_blur=&#8220;41px&#8220; box_shadow_color=&#8220;rgba(0,226,208,0.34)&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las unidades de aire acondicionado multifuncionales pueden utilizarse para la refrigeraci\u00c3\u00b3n y la calefacci\u00c3\u00b3n, tienen una funci\u00c3\u00b3n de deshumidificaci\u00c3\u00b3n del aire y, al mismo tiempo, garantizan la eliminaci\u00c3\u00b3n eficaz de los agentes pat\u00c3\u00b3genos en el aire de la habitaci\u00c3\u00b3n mediante la desinfecci\u00c3\u00b3n UV. <\/p>","protected":false},"author":161,"featured_media":4719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:image {\"align\":\"right\",\"id\":3540,\"width\":427,\"height\":285,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\r\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img src=\"https:\/\/raumluft24.de\/wp-content\/uploads\/2022\/02\/deb12f7d-851e-4de5-8a77-8ed4676456c1.jpg\" alt=\"\" class=\"wp-image-3540\" width=\"427\" height=\"285\"\/><\/figure><\/div>\r\n<!-- \/wp:image -->\r\n\r\n<!-- wp:heading {\"level\":4,\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"800\"}},\"fontSize\":\"medium\"} -->\r\n<h4 class=\"has-medium-font-size\" id=\"saubere-luft-viren-beseitigen-mit-uv-c-licht\" style=\"font-style:normal;font-weight:800\">Saubere Luft - Viren beseitigen mit UV-C Licht<\/h4>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Wenn Sie sich gesund halten m\u00f6chten, ist es f\u00fcr Sie sicherlich selbstverst\u00e4ndlich, Ihr Zuhause durch regelm\u00e4\u00dfige Reinigung und Desinfektion sauber und keimfrei zu halten. Insbesondere Oberfl\u00e4chen und Griffe werden dabei gr\u00fcndlich gereinigt. Sp\u00e4testens seit der Corona-Pandemie ist uns allen aber auch bewusst geworden, welch wichtige Rolle die Virenbelastung unserer Atemluft spielt. Beim Husten und Niesen werden n\u00e4mlich Tropfen, die Viren enthalten k\u00f6nnen, zun\u00e4chst in die Luft geschleudert. Gro\u00dfe, schwere Tropfen sinken recht z\u00fcgig auf den Boden oder Gegenst\u00e4nde ab. Kleinere k\u00f6nnen jedoch mehrere Stunden oder sogar Tage in der Luft schweben. Sie k\u00f6nnen diese daher nicht selbst reinigen, sondern m\u00fcssen auf technische Hilfsmittel zur\u00fcckgreifen. Seit Jahrzehnten bew\u00e4hrt sich daf\u00fcr eine L\u00f6sung, die z. B. auch im medizinischen Bereich eingesetzt wird, mit der Sie Ihre Raumluft sauber und sich selbst damit ein St\u00fcck ges\u00fcnder halten k\u00f6nnen: UV-C-Lampen!<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:heading {\"level\":5,\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"800\"}},\"fontSize\":\"medium\"} -->\r\n<h5 class=\"has-medium-font-size\" id=\"das-wichtigste-im-uberblick\" style=\"font-style:normal;font-weight:800\">Das Wichtigste im \u00dcberblick<\/h5>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:list -->\r\n<ul><li><i class=\"fas fa-check-circle\"><\/i>UV-Licht ist f\u00fcr das menschliche Auge unsichtbar<\/li><li>UV-Licht eliminiert Bakterien und Viren<\/li><li>Luftreinigung durch UV-Licht mit multifunktioneller Klimaanlage<\/li><li>Auch geeignet f\u00fcr gro\u00dfe R\u00e4ume bis zu 60 m2<\/li><\/ul>\r\n<!-- \/wp:list -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:heading {\"level\":5,\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"800\"}},\"fontSize\":\"medium\"} -->\r\n<h5 class=\"has-medium-font-size\" id=\"wie-funktioniert-die-luftreinigung-mit-uv-c-licht\" style=\"font-style:normal;font-weight:800\">Wie funktioniert die Luftreinigung mit UV-C-Licht?<\/h5>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:image {\"align\":\"left\",\"id\":3542,\"width\":427,\"height\":285,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\r\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img src=\"https:\/\/raumluft24.de\/wp-content\/uploads\/2022\/02\/3d58fc6d-7d64-45e5-b492-7e303062334d.jpg\" alt=\"\" class=\"wp-image-3542\" width=\"427\" height=\"285\"\/><\/figure><\/div>\r\n<!-- \/wp:image -->\r\n\r\n<!-- wp:paragraph {\"className\":\"padding-top: 20px\"} -->\r\n<p class=\"padding-top: 20px\">Ultraviolettes Licht ist f\u00fcr das menschliche Auge nicht sichtbar. Vielleicht wissen Sie, dass dieses Licht auch im Solarium zum Einsatz kommt. Allerdings handelt es sich dabei um die l\u00e4ngeren Strahlenarten UV-A und UV-B. Die k\u00fcrzeste Wellenl\u00e4nge, die UV-C-Strahlung, ist hingegen das Licht, welches eingesetzt wird, um Wasser, Gegenst\u00e4nde und die Luft zu desinfizieren. Lebewesen sollten diesem Licht nicht permanent ausgesetzt werden, da die Hautalterung dadurch beschleunigt werden kann.<br>Eingebaut in Klimaanlagen wird die Luft aber vollkommen sicher innerhalb des Ger\u00e4ts an den UV-C-Lampen vorbeigeschleust, womit keine Gefahr f\u00fcr anwesende Personen im Raum besteht. Es ist eine \u00e4u\u00dferst effektive Methode, um diverse Krankheitserreger wie Viren, Bakterien und Schimmelpilze abzut\u00f6ten: Die UV-Lampe kann bis zu 99,9 % der enthaltenen Bakterien und Viren abt\u00f6ten, indem es die molekularen Bestandteile der Mikroorganismen zerst\u00f6rt. Innerhalb von Sekunden werden diese inaktiv. Diese Art der Desinfektion birgt den Vorteil, ohne den Einsatz gef\u00e4hrlicher chemischer Substanzen auszukommen!<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:heading {\"level\":5,\"style\":{\"typography\":{\"fontStyle\":\"normal\",\"fontWeight\":\"800\"}},\"fontSize\":\"medium\"} -->\r\n<h5 class=\"has-medium-font-size\" id=\"klimaanlagen-malpensa-und-elba-mini-reinigen-luft-mit-uv-technik\" style=\"font-style:normal;font-weight:800\">Klimaanlagen Malpensa und Elba Mini reinigen Luft mit UV-Technik<\/h5>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Wenn Sie gerne f\u00fcr hygienisch reine Luft bei Ihnen Zuhause oder in gewerblichen R\u00e4umen sorgen wollen, empfehlen wir Ihnen unsere <a href=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-malpensa-in12hp-uv\/\" data-type=\"URL\" data-id=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-malpensa-in12hp-uv\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wandklimaanlage Malpensa mit integrierter UV-C-Lampe<\/a> sowie unsere <a href=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-elba-mini-inhp09-mit-uv-technik\/\" data-type=\"URL\" data-id=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-elba-mini-inhp09-mit-uv-technik\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klimaanlage Elba Mini mit integrierter UV-C Lampe<\/a>. Die Multifunktions-Klimager\u00e4te k\u00f6nnen selbstverst\u00e4ndlich zum K\u00fchlen und Heizen genutzt werden, haben eine Luftentfeuchtungsfunktion und sorgen gleichzeitig f\u00fcr eine effektive Abt\u00f6tung von Krankheitserregern in der Raumluft mittels UV-Entkeimung. Neben der Installation in Privatr\u00e4umen f\u00fcr die eigene Gesundheit, bietet sich die Klimaanlage mit UV-Lampe auch im Hotelgewerbe an, um die Aerosole wechselnder Hotelg\u00e4ste zu neutralisieren. Zudem sind die Klimaanlagen Malpensa und Elba Mini f\u00fcr R\u00e4ume von 30 m\u00b2 -60m2 geeignet, wodurch das Produkt auch f\u00fcr Klassenr\u00e4ume, kleinere Gastronomie-Betriebe sowie B\u00fcros oder Besprechungsr\u00e4ume interessant ist.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Wie bei unseren Wandklimager\u00e4ten \u00fcblich, sind auch die Modelle Malpensa und Elba Mini leistungsstark und dabei extrem leise (27 - 43 Dezibel). Die Installation ist einfach und schnell und erfolgt vor allem ohne Au\u00dfenger\u00e4t an Ihrer Fassade. Sie k\u00f6nnen die Montageh\u00f6he grunds\u00e4tzlich selbst w\u00e4hlen. Mit seiner wei\u00dfen Lackierung und dem schlichten Monoblock-Design sehen die Klimaanlagen Malpensa und Elba Mini schick und unaufdringlich aus.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:buttons -->\r\n<div class=\"wp-block-buttons\"><!-- wp:button \/--><\/div>\r\n<!-- \/wp:buttons -->\r\n\r\n<!-- wp:group -->\r\n<div class=\"wp-block-group\"><!-- wp:buttons -->\r\n<div class=\"wp-block-buttons\"><!-- wp:button {\"gradient\":\"light-green-cyan-to-vivid-green-cyan\"} -->\r\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background\" href=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-malpensa-in12hp-uv\/\" target=\"_blank\" rel=\"noreferrer noopener\">MALPENSA im Shop ansehen<\/a><\/div>\r\n<!-- \/wp:button -->\r\n\r\n<!-- wp:button {\"gradient\":\"light-green-cyan-to-vivid-green-cyan\"} -->\r\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background\" href=\"https:\/\/raumluft24.de\/produkt\/klimaanlage-elba-mini-inhp09-mit-uv-technik\/\" target=\"_blank\" rel=\"noreferrer noopener\">ELBA MINI im Shop ansehen<\/a><\/div>\r\n<!-- \/wp:button --><\/div>\r\n<!-- \/wp:buttons --><\/div>\r\n<!-- \/wp:group -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><\/p>\r\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/posts\/3267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/comments?post=3267"}],"version-history":[{"count":10,"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/posts\/3267\/revisions"}],"predecessor-version":[{"id":6258,"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/posts\/3267\/revisions\/6258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/media\/4719"}],"wp:attachment":[{"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/media?parent=3267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/categories?post=3267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/raumluft24.de\/es\/wp-json\/wp\/v2\/tags?post=3267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}